{"id":212,"count":30,"description":"","link":"https:\/\/guide.mwt.co.jp\/businessclass\/news\/tour\/","name":"\u304a\u3059\u3059\u3081\u30c4\u30a2\u30fc\u60c5\u5831","slug":"tour","taxonomy":"category","parent":2,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/guide.mwt.co.jp\/businessclass\/wp-json\/wp\/v2\/categories\/212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.mwt.co.jp\/businessclass\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/guide.mwt.co.jp\/businessclass\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/guide.mwt.co.jp\/businessclass\/wp-json\/wp\/v2\/categories\/2"}],"wp:post_type":[{"href":"https:\/\/guide.mwt.co.jp\/businessclass\/wp-json\/wp\/v2\/posts?categories=212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}